{"id":671,"date":"2024-12-03T08:15:52","date_gmt":"2024-12-03T07:15:52","guid":{"rendered":"https:\/\/sametpolat.com\/portfolio\/relaunch-von-corporate-hartmann-info-und-hartmann-info\/"},"modified":"2024-12-03T18:07:38","modified_gmt":"2024-12-03T17:07:38","slug":"relaunch-von-corporate-hartmann-info-und-hartmann-info","status":"publish","type":"portfolio","link":"https:\/\/sametpolat.com\/de\/portfolio\/relaunch-von-corporate-hartmann-info-und-hartmann-info\/","title":{"rendered":"Relaunch von corporate.hartmann.info und hartmann.info"},"content":{"rendered":"<p>Als Projektleiter habe ich den kompletten Relaunch der Unternehmenswebsite <strong>corporate.hartmann.info<\/strong> und der globalen Produkt- und Serviceplattform <strong>hartmann.info<\/strong> geleitet. In dieser Rolle war ich f\u00fcr die Leitung eines interdisziplin\u00e4ren Agenturteams verantwortlich, zu dem UX\/UI-Designer, Content-Spezialisten und digitale Strategen geh\u00f6rten. <\/p><p>Mein prim\u00e4res Ziel war es, die Plattformen sowohl technisch als auch visuell zu modernisieren, um sicherzustellen, dass die Marke HARTMANN und ihre Dienstleistungen im digitalen Raum wirkungsvoll pr\u00e4sentiert werden. Ich entwickelte und implementierte die \u00fcbergreifende Projektstrategie und stellte sicher, dass alle Meilensteine p\u00fcnktlich und innerhalb des Budgets erreicht wurden. <\/p><h2 class=\"wp-block-heading\"><br\/><strong>Hauptverantwortlichkeiten und Erfolge:<\/strong><\/h2><p><strong>Teamleitung:<\/strong> Koordinierte ein Agenturteam von \u00fcber 10 Fachleuten und sorgte f\u00fcr nahtlose Arbeitsabl\u00e4ufe und klare Kommunikation zwischen den Abteilungen.<\/p><p>&#8211; <strong>Projektplanung und -management:<\/strong> Erstellung detaillierter Projektzeitpl\u00e4ne, \u00dcberwachung von Budgets und effektives Risikomanagement.<\/p><p>&#8211; <strong>Management von Interessengruppen:<\/strong> Arbeitete eng mit internen Teams und externen Stakeholdern zusammen, um Anforderungen zu erfassen, Feedback zu integrieren und Projektziele abzustimmen.<\/p><p>&#8211; <strong>Migration von Inhalten:<\/strong> Leitete die Migration umfangreicher Inhalte und optimierte sie sowohl f\u00fcr SEO als auch f\u00fcr die Benutzerfreundlichkeit.<\/p><p>&#8211; <strong>UX- und UI-Optimierung:<\/strong> In enger Zusammenarbeit mit den UX-Designern haben wir f\u00fcr ein modernes, benutzerfreundliches Design gesorgt.<\/p><p>&#8211; <strong>Tests und Einf\u00fchrung:<\/strong> Organisierte und f\u00fchrte gr\u00fcndliche Testphasen durch, um eine einwandfreie Funktionalit\u00e4t und Leistung vor dem Go-Live zu gew\u00e4hrleisten.<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"758\" height=\"426\" src=\"https:\/\/sametpolat.com\/wp-content\/uploads\/2022\/06\/hartmann-info-platform-digital-strategy.jpg\" alt=\"\" class=\"wp-image-474\" srcset=\"https:\/\/sametpolat.com\/wp-content\/uploads\/2022\/06\/hartmann-info-platform-digital-strategy.jpg 758w, https:\/\/sametpolat.com\/wp-content\/uploads\/2022\/06\/hartmann-info-platform-digital-strategy-300x169.jpg 300w, https:\/\/sametpolat.com\/wp-content\/uploads\/2022\/06\/hartmann-info-platform-digital-strategy-600x337.jpg 600w\" sizes=\"(max-width: 758px) 100vw, 758px\" \/><\/figure><\/div><h2 class=\"wp-block-heading\"><strong>Verwendete Fertigkeiten:<\/strong><\/h2><p>&#8211; <strong>Agiles Projektmanagement:<\/strong> Erfolgreiche Implementierung agiler Methoden wie Scrum und Kanban, um flexible und effiziente Projektabl\u00e4ufe zu erm\u00f6glichen.<\/p><p>&#8211; <strong>F\u00fchrung und Kommunikation:<\/strong> F\u00fchrte das Team mit einer klaren Vision und proaktiver Unterst\u00fctzung durch alle Projektphasen.<\/p><p>&#8211; <strong>Technisches Fachwissen:<\/strong> Zusammenarbeit mit Entwicklungsteams zur Integration moderner Webtechnologien und -standards.<\/p><p>&#8211; <strong>Strategische Planung:<\/strong> Wir entwarfen eine umfassende Roadmap f\u00fcr den Relaunch, die sowohl auf die kurz- als auch auf die langfristigen Gesch\u00e4ftsziele abgestimmt war.<\/p><p>&#8211; <strong>SEO und Inhaltsstrategie:<\/strong> Verbesserte Website-Inhalte, um die Sichtbarkeit zu verbessern und eine ansprechende Benutzererfahrung zu bieten.<\/p><p>Das Projekt f\u00fchrte zu einem modernen, zukunftsf\u00e4higen digitalen Auftritt f\u00fcr die HARTMANN-Gruppe, der die Markenwahrnehmung und das Engagement der Nutzer deutlich verbessert.<\/p><div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><\/div><div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Als Projektleiter habe ich den kompletten Relaunch der Unternehmenswebsite corporate.hartmann.info und der globalen Produkt- und Serviceplattform hartmann.info&#8230;<\/p>\n","protected":false},"author":1,"featured_media":627,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"portfolio_category":[118,125],"class_list":["post-671","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-projektleitung","portfolio_category-website-de"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sametpolat.com\/de\/wp-json\/wp\/v2\/portfolio\/671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sametpolat.com\/de\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/sametpolat.com\/de\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/sametpolat.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sametpolat.com\/de\/wp-json\/wp\/v2\/comments?post=671"}],"version-history":[{"count":2,"href":"https:\/\/sametpolat.com\/de\/wp-json\/wp\/v2\/portfolio\/671\/revisions"}],"predecessor-version":[{"id":675,"href":"https:\/\/sametpolat.com\/de\/wp-json\/wp\/v2\/portfolio\/671\/revisions\/675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sametpolat.com\/de\/wp-json\/wp\/v2\/media\/627"}],"wp:attachment":[{"href":"https:\/\/sametpolat.com\/de\/wp-json\/wp\/v2\/media?parent=671"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/sametpolat.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}